{"id":1531,"date":"2022-09-28T14:21:00","date_gmt":"2022-09-28T13:21:00","guid":{"rendered":"https:\/\/www.phgd.group\/?p=1531"},"modified":"2026-08-17T14:04:34","modified_gmt":"2026-08-17T13:04:34","slug":"un-objectif-culture-est-essentiel-pour-notre-avenir-commun","status":"publish","type":"post","link":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/","title":{"rendered":"Un objectif culture est essentiel pour notre avenir commun"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1531\" class=\"elementor elementor-1531\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52f7915 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52f7915\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6e3e79\" data-id=\"a6e3e79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ebd33b elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"2ebd33b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Un objectif culture est essentiel pour notre avenir commun<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56385db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56385db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c97bca\" data-id=\"2c97bca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a5dd9c elementor-widget elementor-widget-image\" data-id=\"5a5dd9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/culture2030goal.net\/sites\/default\/files\/2023-02\/culture2030goal_Culture%20Goral%20-%20FRA.pdf\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/phgd.group\/wp-content\/uploads\/2022\/09\/Culture-Goal-Report-2022-French-212x300.jpg\" class=\"attachment-medium size-medium wp-image-1534\" alt=\"\" srcset=\"https:\/\/phgd.group\/wp-content\/uploads\/2022\/09\/Culture-Goal-Report-2022-French-212x300.jpg 212w, https:\/\/phgd.group\/wp-content\/uploads\/2022\/09\/Culture-Goal-Report-2022-French-725x1024.jpg 725w, https:\/\/phgd.group\/wp-content\/uploads\/2022\/09\/Culture-Goal-Report-2022-French-768x1085.jpg 768w, https:\/\/phgd.group\/wp-content\/uploads\/2022\/09\/Culture-Goal-Report-2022-French-8x12.jpg 8w, https:\/\/phgd.group\/wp-content\/uploads\/2022\/09\/Culture-Goal-Report-2022-French.jpg 1079w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Cliquer sur la couverture pour acc\u00e9der au texte int\u00e9gral du rapport.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30399a9\" data-id=\"30399a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae7f557 elementor-widget elementor-widget-spacer\" data-id=\"ae7f557\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-515cea9 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"515cea9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tLa conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s'est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l'occasion de discuter du r\u00f4le de la culture dans l'agenda du d\u00e9veloppement durable des Nations-Unies.\n\nLors de la conf\u00e9rence, l'ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eda0bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eda0bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a02a1ce\" data-id=\"a02a1ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c95fa42 elementor-widget elementor-widget-text-editor\" data-id=\"c95fa42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>R\u00e9dig\u00e9 par John Crowley dans le cadre d&rsquo;un contrat en la CGLU et PHGD, le document analyse les raisons pour lesquelles le culture n&rsquo;a pas \u00e9t\u00e9 sp\u00e9cifiquement int\u00e9gr\u00e9e, avec un Objectif qui lui soit consacr\u00e9, dans les ODD adopt\u00e9s par les Nations-Unies en 2015.<\/p><p>Il souligne ensuite les raisons pour lesquelles la culture est au centre de toutes les pr\u00e9occupations de d\u00e9veloppement, et \u00e0 ce titre m\u00e9rite une reconnaissance formelle dans les ODD par le biais d&rsquo;un Objectif.<\/p><p>Enfin, le rapport propose une premi\u00e8re r\u00e9daction de qui pourrait \u00e0 terme devenir un tel Objectif et esquisse quelques \u00e9l\u00e9ments n\u00e9cessaires de strat\u00e9gie pour en favoriser l&rsquo;adoption internationale.<\/p><p>Ce travail sur la culture et ses transformations se situe au c\u0153ur de la mission de PHGD : contribuer \u00e0 la compr\u00e9hensions des transformations pour favoriser des r\u00e9ponses strat\u00e9giques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s&rsquo;est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l&rsquo;occasion de discuter du r\u00f4le de la culture dans l&rsquo;agenda du d\u00e9veloppement durable des Nations-Unies.<\/p>\n<p>Lors de la conf\u00e9rence, l&rsquo;ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"_eb_attr":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"page_builder":"","footnotes":""},"categories":[136,134],"tags":[24,29,31,23,27,9,28,30,25,26],"class_list":["post-1531","post","type-post","status-publish","format-standard","hentry","category-odd-culture-phgd","category-phgd","tag-2030-agenda","tag-advocacy","tag-consulting","tag-culture","tag-culture-goal","tag-publication","tag-sdg18","tag-sustainable-development","tag-uclg","tag-un"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s&#039;est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l&#039;occasion de discuter du r\u00f4le de la culture dans l&#039;agenda du d\u00e9veloppement durable des Nations-Unies. Lors de la conf\u00e9rence, l&#039;ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"jcphgd@gmail.com\"\/>\n\t<meta name=\"google-site-verification\" content=\"wq65Z8sNQbZ2bPb-Od5kYCBRdCpiNYx7XWInmTbZxgA\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"PHGD - Produire mieux, consommer moins\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Un objectif culture est essentiel pour notre avenir commun\" \/>\n\t\t<meta property=\"og:description\" content=\"La conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s&#039;est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l&#039;occasion de discuter du r\u00f4le de la culture dans l&#039;agenda du d\u00e9veloppement durable des Nations-Unies. Lors de la conf\u00e9rence, l&#039;ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.phgd.group\/wp-content\/uploads\/2021\/03\/PHGD-logo-e1616263981215.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.phgd.group\/wp-content\/uploads\/2021\/03\/PHGD-logo-e1616263981215.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-09-28T13:21:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-17T13:04:34+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1DksXuPYMx\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@GroupPhgd\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Un objectif culture est essentiel pour notre avenir commun\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s&#039;est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l&#039;occasion de discuter du r\u00f4le de la culture dans l&#039;agenda du d\u00e9veloppement durable des Nations-Unies. Lors de la conf\u00e9rence, l&#039;ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@GroupPhgd\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.phgd.group\/wp-content\/uploads\/2021\/03\/PHGD-logo-e1616263981215.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#blogposting\",\"name\":\"Un objectif culture est essentiel pour notre avenir commun\",\"headline\":\"Un objectif culture est essentiel pour notre avenir commun\",\"author\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/author\\\/jcphgdgmail-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.phgd.group\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Culture-Goal-Report-2022-French-212x300.jpg\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#articleImage\"},\"datePublished\":\"2022-09-28T14:21:00+01:00\",\"dateModified\":\"2026-08-17T14:04:34+01:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#webpage\"},\"articleSection\":\"ODD Culture, PHGD, 2030 Agenda, advocacy, consulting, culture, Culture goal, Publication, SDG18, sustainable development, UCLG, UN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/phgd.group\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/category\\\/phgd\\\/#listItem\",\"name\":\"PHGD\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/category\\\/phgd\\\/#listItem\",\"position\":2,\"name\":\"PHGD\",\"item\":\"https:\\\/\\\/phgd.group\\\/en\\\/category\\\/phgd\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/category\\\/phgd\\\/odd-culture-phgd\\\/#listItem\",\"name\":\"ODD Culture\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/category\\\/phgd\\\/odd-culture-phgd\\\/#listItem\",\"position\":3,\"name\":\"ODD Culture\",\"item\":\"https:\\\/\\\/phgd.group\\\/en\\\/category\\\/phgd\\\/odd-culture-phgd\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#listItem\",\"name\":\"Un objectif culture est essentiel pour notre avenir commun\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/category\\\/phgd\\\/#listItem\",\"name\":\"PHGD\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#listItem\",\"position\":4,\"name\":\"Un objectif culture est essentiel pour notre avenir commun\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/category\\\/phgd\\\/odd-culture-phgd\\\/#listItem\",\"name\":\"ODD Culture\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/#organization\",\"name\":\"PHGD\",\"description\":\"Le Groupe PHGD d\\u00e9veloppe des id\\u00e9es et des technologies pour produire mieux, consommer moins.\",\"url\":\"https:\\\/\\\/phgd.group\\\/en\\\/\",\"email\":\"contact@phgd.fr\",\"telephone\":\"+33664293993\",\"foundingDate\":\"2020-10-22\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":1,\"maxValue\":10},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.phgd.group\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/PHGD-logo-e1616263981215.png\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/share\\\/1DksXuPYMx\\\/\",\"https:\\\/\\\/x.com\\\/GroupPhgd\",\"https:\\\/\\\/www.youtube.com\\\/@phgd8736\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/phgd-group\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/author\\\/jcphgdgmail-com\\\/#author\",\"url\":\"https:\\\/\\\/phgd.group\\\/en\\\/author\\\/jcphgdgmail-com\\\/\",\"name\":\"jcphgd@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5ccf2bbc781c091bc9b30e3341fdd32d9caaec71dc0fba6769f71723f29a218e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"jcphgd@gmail.com\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#webpage\",\"url\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/\",\"name\":\"Un objectif culture est essentiel pour notre avenir commun\",\"description\":\"La conf\\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s'est tenue \\u00e0 Mexico en septembre 2022, a donn\\u00e9 l'occasion de discuter du r\\u00f4le de la culture dans l'agenda du d\\u00e9veloppement durable des Nations-Unies. Lors de la conf\\u00e9rence, l'ONG Cit\\u00e9s et Gouvernements Locaux Unis a diffus\\u00e9 un document de plaidoyer qui appelle \\u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/2022\\\/09\\\/28\\\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/author\\\/jcphgdgmail-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/author\\\/jcphgdgmail-com\\\/#author\"},\"datePublished\":\"2022-09-28T14:21:00+01:00\",\"dateModified\":\"2026-08-17T14:04:34+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/phgd.group\\\/en\\\/\",\"name\":\"PHGD\",\"alternateName\":\"PHGD\",\"description\":\"Produire mieux, consommer moins\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/phgd.group\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Un objectif culture est essentiel pour notre avenir commun<\/title>\n\n","aioseo_head_json":{"title":"Un objectif culture est essentiel pour notre avenir commun","description":"La conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s'est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l'occasion de discuter du r\u00f4le de la culture dans l'agenda du d\u00e9veloppement durable des Nations-Unies. Lors de la conf\u00e9rence, l'ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.","canonical_url":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"wq65Z8sNQbZ2bPb-Od5kYCBRdCpiNYx7XWInmTbZxgA","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#blogposting","name":"Un objectif culture est essentiel pour notre avenir commun","headline":"Un objectif culture est essentiel pour notre avenir commun","author":{"@id":"https:\/\/phgd.group\/en\/author\/jcphgdgmail-com\/#author"},"publisher":{"@id":"https:\/\/phgd.group\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.phgd.group\/wp-content\/uploads\/2022\/09\/Culture-Goal-Report-2022-French-212x300.jpg","@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#articleImage"},"datePublished":"2022-09-28T14:21:00+01:00","dateModified":"2026-08-17T14:04:34+01:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#webpage"},"isPartOf":{"@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#webpage"},"articleSection":"ODD Culture, PHGD, 2030 Agenda, advocacy, consulting, culture, Culture goal, Publication, SDG18, sustainable development, UCLG, UN"},{"@type":"BreadcrumbList","@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/phgd.group\/en#listItem","position":1,"name":"Home","item":"https:\/\/phgd.group\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/phgd.group\/en\/category\/phgd\/#listItem","name":"PHGD"}},{"@type":"ListItem","@id":"https:\/\/phgd.group\/en\/category\/phgd\/#listItem","position":2,"name":"PHGD","item":"https:\/\/phgd.group\/en\/category\/phgd\/","nextItem":{"@type":"ListItem","@id":"https:\/\/phgd.group\/en\/category\/phgd\/odd-culture-phgd\/#listItem","name":"ODD Culture"},"previousItem":{"@type":"ListItem","@id":"https:\/\/phgd.group\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/phgd.group\/en\/category\/phgd\/odd-culture-phgd\/#listItem","position":3,"name":"ODD Culture","item":"https:\/\/phgd.group\/en\/category\/phgd\/odd-culture-phgd\/","nextItem":{"@type":"ListItem","@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#listItem","name":"Un objectif culture est essentiel pour notre avenir commun"},"previousItem":{"@type":"ListItem","@id":"https:\/\/phgd.group\/en\/category\/phgd\/#listItem","name":"PHGD"}},{"@type":"ListItem","@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#listItem","position":4,"name":"Un objectif culture est essentiel pour notre avenir commun","previousItem":{"@type":"ListItem","@id":"https:\/\/phgd.group\/en\/category\/phgd\/odd-culture-phgd\/#listItem","name":"ODD Culture"}}]},{"@type":"Organization","@id":"https:\/\/phgd.group\/en\/#organization","name":"PHGD","description":"Le Groupe PHGD d\u00e9veloppe des id\u00e9es et des technologies pour produire mieux, consommer moins.","url":"https:\/\/phgd.group\/en\/","email":"contact@phgd.fr","telephone":"+33664293993","foundingDate":"2020-10-22","numberOfEmployees":{"@type":"QuantitativeValue","minValue":1,"maxValue":10},"logo":{"@type":"ImageObject","url":"https:\/\/www.phgd.group\/wp-content\/uploads\/2021\/03\/PHGD-logo-e1616263981215.png","@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#organizationLogo"},"image":{"@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/share\/1DksXuPYMx\/","https:\/\/x.com\/GroupPhgd","https:\/\/www.youtube.com\/@phgd8736","https:\/\/fr.linkedin.com\/company\/phgd-group"]},{"@type":"Person","@id":"https:\/\/phgd.group\/en\/author\/jcphgdgmail-com\/#author","url":"https:\/\/phgd.group\/en\/author\/jcphgdgmail-com\/","name":"jcphgd@gmail.com","image":{"@type":"ImageObject","@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/5ccf2bbc781c091bc9b30e3341fdd32d9caaec71dc0fba6769f71723f29a218e?s=96&d=mm&r=g","width":96,"height":96,"caption":"jcphgd@gmail.com"}},{"@type":"WebPage","@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#webpage","url":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/","name":"Un objectif culture est essentiel pour notre avenir commun","description":"La conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s'est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l'occasion de discuter du r\u00f4le de la culture dans l'agenda du d\u00e9veloppement durable des Nations-Unies. Lors de la conf\u00e9rence, l'ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/phgd.group\/en\/#website"},"breadcrumb":{"@id":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/#breadcrumblist"},"author":{"@id":"https:\/\/phgd.group\/en\/author\/jcphgdgmail-com\/#author"},"creator":{"@id":"https:\/\/phgd.group\/en\/author\/jcphgdgmail-com\/#author"},"datePublished":"2022-09-28T14:21:00+01:00","dateModified":"2026-08-17T14:04:34+01:00"},{"@type":"WebSite","@id":"https:\/\/phgd.group\/en\/#website","url":"https:\/\/phgd.group\/en\/","name":"PHGD","alternateName":"PHGD","description":"Produire mieux, consommer moins","inLanguage":"en-GB","publisher":{"@id":"https:\/\/phgd.group\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"PHGD - Produire mieux, consommer moins","og:type":"article","og:title":"Un objectif culture est essentiel pour notre avenir commun","og:description":"La conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s'est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l'occasion de discuter du r\u00f4le de la culture dans l'agenda du d\u00e9veloppement durable des Nations-Unies. Lors de la conf\u00e9rence, l'ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.","og:url":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/","og:image":"https:\/\/www.phgd.group\/wp-content\/uploads\/2021\/03\/PHGD-logo-e1616263981215.png","og:image:secure_url":"https:\/\/www.phgd.group\/wp-content\/uploads\/2021\/03\/PHGD-logo-e1616263981215.png","article:published_time":"2022-09-28T13:21:00+00:00","article:modified_time":"2026-08-17T13:04:34+00:00","article:publisher":"https:\/\/www.facebook.com\/share\/1DksXuPYMx\/","twitter:card":"summary_large_image","twitter:site":"@GroupPhgd","twitter:title":"Un objectif culture est essentiel pour notre avenir commun","twitter:description":"La conf\u00e9rence mondiale sur les politiques culturelles, Mondiacult, qui s'est tenue \u00e0 Mexico en septembre 2022, a donn\u00e9 l'occasion de discuter du r\u00f4le de la culture dans l'agenda du d\u00e9veloppement durable des Nations-Unies. Lors de la conf\u00e9rence, l'ONG Cit\u00e9s et Gouvernements Locaux Unis a diffus\u00e9 un document de plaidoyer qui appelle \u00e0 un Objectif Culture comme composante essentielle de notre avenir commun.","twitter:creator":"@GroupPhgd","twitter:image":"https:\/\/www.phgd.group\/wp-content\/uploads\/2021\/03\/PHGD-logo-e1616263981215.png"},"aioseo_meta_data":{"post_id":"1531","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-08-17 13:04:59","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2025-12-22 14:36:20","updated":"2026-08-17 13:26:59","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/phgd.group\/en\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/phgd.group\/en\/category\/phgd\/\" title=\"PHGD\">PHGD<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/phgd.group\/en\/category\/phgd\/odd-culture-phgd\/\" title=\"ODD Culture\">ODD Culture<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tUn objectif culture est essentiel pour notre avenir commun\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/phgd.group\/en"},{"label":"PHGD","link":"https:\/\/phgd.group\/en\/category\/phgd\/"},{"label":"ODD Culture","link":"https:\/\/phgd.group\/en\/category\/phgd\/odd-culture-phgd\/"},{"label":"Un objectif culture est essentiel pour notre avenir commun","link":"https:\/\/phgd.group\/en\/2022\/09\/28\/un-objectif-culture-est-essentiel-pour-notre-avenir-commun\/"}],"_links":{"self":[{"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/posts\/1531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/comments?post=1531"}],"version-history":[{"count":1,"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/posts\/1531\/revisions"}],"predecessor-version":[{"id":3958,"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/posts\/1531\/revisions\/3958"}],"wp:attachment":[{"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/media?parent=1531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/categories?post=1531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phgd.group\/en\/wp-json\/wp\/v2\/tags?post=1531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}